{"id":967,"date":"2009-10-14T04:47:11","date_gmt":"2009-10-14T09:47:11","guid":{"rendered":"http:\/\/www.enigmatium.com\/blog\/?p=967"},"modified":"2016-09-08T18:32:48","modified_gmt":"2016-09-08T16:32:48","slug":"homonimos","status":"publish","type":"post","link":"https:\/\/www.enigmatium.com\/blog\/homonimos\/","title":{"rendered":"Hom\u00f3nimos"},"content":{"rendered":"<p>Los hom\u00f3nimos son palabras o frases que contienen las mismas letras, en el mismo orden, pero con significados diferentes. Descubre las parejas de hom\u00f3nimos con ayuda\u00a0de las pistas.<\/p>\n<p>1.- Parte del barco \/ Cilindro de cera que da luz.<\/p>\n<p>2.- Asiento con respaldo \/ Establecimiento que guarda dinero.<\/p>\n<p>3.- Luz que emite fuego \/ Mam\u00edfero americano.<\/p>\n<p>4.- \u00c1rbol de la familia de las fag\u00e1ceas \/ Presente subjuntivo de haber.<\/p>\n<p>5.- Rabo \/ Pasta para pegar.<\/p>\n<p>6.- Juguete \/ Parte del brazo.<\/p>\n<p>7.- Vaso con pie \/ Parte m\u00e1s alta del \u00e1rbol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los hom\u00f3nimos son palabras o frases que contienen las mismas letras, en el mismo orden, pero con significados diferentes. Descubre las parejas de hom\u00f3nimos con ayuda\u00a0de las pistas. 1.- Parte del barco \/ Cilindro de cera que da luz. 2.- Asiento con respaldo \/ Establecimiento que guarda dinero. 3.- Luz que emite fuego \/ Mam\u00edfero americano. 4.- \u00c1rbol de la familia de las fag\u00e1ceas \/ Presente subjuntivo de haber. 5.- Rabo \/ Pasta para pegar. 6.- Juguete \/ Parte del&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/posts\/967"}],"collection":[{"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/comments?post=967"}],"version-history":[{"count":4,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/posts\/967\/revisions"}],"predecessor-version":[{"id":4347,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/posts\/967\/revisions\/4347"}],"wp:attachment":[{"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/media?parent=967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/categories?post=967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/tags?post=967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}