{"id":996,"date":"2009-11-03T05:28:31","date_gmt":"2009-11-03T10:28:31","guid":{"rendered":"http:\/\/www.enigmatium.com\/blog\/?p=996"},"modified":"2013-11-20T17:39:27","modified_gmt":"2013-11-20T16:39:27","slug":"juegos-de-palabras-2","status":"publish","type":"post","link":"https:\/\/www.enigmatium.com\/blog\/juegos-de-palabras-2\/","title":{"rendered":"Palabras para jugar"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-997\" alt=\"palabras para jugar\" src=\"https:\/\/www.enigmatium.com\/blog\/wp-content\/uploads\/2009\/11\/37.jpg\" width=\"180\" height=\"120\" \/><\/p>\n<p style=\"text-align: center;\">Juegos de palabras<\/p>\n<p style=\"text-align: left;\">Este juego consiste en transformar una palabra en otra cambiando una sola letra en cada paso, de modo que en cada pelda\u00f1o de la escalera aparezca una palabra nueva.<\/p>\n<p style=\"text-align: left;\">De PALO a GATA.<\/p>\n<p style=\"text-align: right;\">PALO<\/p>\n<p style=\"text-align: right;\">1. Cuac<\/p>\n<p style=\"text-align: right;\">2. Una de la mesa<\/p>\n<p style=\"text-align: right;\">GATA<\/p>\n<p style=\"text-align: left;\">De CELTA a CARDO.<\/p>\n<p style=\"text-align: right;\">CELTA<\/p>\n<p style=\"text-align: right;\">1. Aposento para presos.<\/p>\n<p style=\"text-align: right;\">2. Pelo grueso<\/p>\n<p style=\"text-align: right;\">3. Torpe<\/p>\n<p style=\"text-align: right;\">4. Gordura<\/p>\n<p style=\"text-align: right;\">5. Acci\u00f3n de cardar<\/p>\n<p style=\"text-align: right;\">CARDO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juegos de palabras Este juego consiste en transformar una palabra en otra cambiando una sola letra en cada paso, de modo que en cada pelda\u00f1o de la escalera aparezca una palabra nueva. De PALO a GATA. PALO 1. Cuac 2. Una de la mesa GATA De CELTA a CARDO. CELTA 1. Aposento para presos. 2. Pelo grueso 3. Torpe 4. Gordura 5. Acci\u00f3n de cardar CARDO<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/posts\/996"}],"collection":[{"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":9,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/posts\/996\/revisions"}],"predecessor-version":[{"id":4132,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/posts\/996\/revisions\/4132"}],"wp:attachment":[{"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/media?parent=996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/categories?post=996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enigmatium.com\/blog\/wp-json\/wp\/v2\/tags?post=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}